{"id":18,"date":"2024-07-11T17:59:43","date_gmt":"2024-07-11T15:59:43","guid":{"rendered":"https:\/\/www.wowven.co.za\/new\/?page_id=18"},"modified":"2026-04-09T12:07:18","modified_gmt":"2026-04-09T10:07:18","slug":"contact-us-2","status":"publish","type":"page","link":"https:\/\/www.wowven.co.za\/new\/contact-us-2\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1775726148476{padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;]<figure class=\"vcex-image vcex-module\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"688\" height=\"1032\" src=\"https:\/\/www.wowven.co.za\/new\/wp-content\/uploads\/Mandjie-33-4.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.wowven.co.za\/new\/wp-content\/uploads\/Mandjie-33-4.jpg 688w, https:\/\/www.wowven.co.za\/new\/wp-content\/uploads\/Mandjie-33-4-600x900.jpg 600w, https:\/\/www.wowven.co.za\/new\/wp-content\/uploads\/Mandjie-33-4-400x600.jpg 400w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/div><\/figure><div class=\"vcex-spacing wpex-w-100 wpex-clear\"><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]\n<h1>Contact Us<\/h1>\n[\/vc_column_text]<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:15px;\"><\/div><div class=\"vcex-list_item vcex-module wpex-m-0 wpex-max-w-100 wpex-mb-5\"><div class=\"vcex-list-item-inner wpex-inline-flex wpex-flex-no-wrap\"><div class=\"vcex-list-item-icon wpex-mr-10\"><div class=\"vcex-list-item-icon-inner vcex-icon-wrap wpex-inline-flex wpex-justify-center wpex-items-center wpex-leading-none wpex-child-inherit-color\"><span class=\"wpex-icon--w wpex-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path d=\"M22.286 2.286q2.125 0 3.634 1.509t1.509 3.634v17.143q0 2.125-1.509 3.634t-3.634 1.509h-17.143q-2.125 0-3.634-1.509t-1.509-3.634v-17.143q0-2.125 1.509-3.634t3.634-1.509h17.143zM22.857 21.143v-7.786q-0.554 0.625-1.143 0.982-0.607 0.393-2.366 1.518t-2.705 1.768q-1.75 1.232-2.929 1.232v0 0q-1.179 0-2.929-1.232-0.839-0.571-2.536-1.652t-2.536-1.652q-0.214-0.143-0.589-0.482t-0.554-0.482v7.786q0 0.714 0.5 1.214t1.214 0.5h14.857q0.714 0 1.214-0.5t0.5-1.214zM22.857 10.911q0-0.732-0.491-1.25t-1.223-0.518h-14.857q-0.714 0-1.214 0.5t-0.5 1.214q0 0.661 0.545 1.366t1.205 1.152q0.839 0.571 2.455 1.589t2.313 1.482q0.054 0.036 0.304 0.205t0.375 0.25 0.375 0.232 0.42 0.232 0.384 0.17 0.402 0.134 0.366 0.045 0.366-0.045 0.402-0.134 0.384-0.17 0.42-0.232 0.375-0.232 0.375-0.25 0.304-0.205l4.768-3.107q0.625-0.411 1.188-1.116t0.563-1.313z\"><\/path><\/svg><\/span><\/div><\/div><div class=\"vcex-list-item-text vcex-content wpex-flex-grow\">Email: info@wowven.co.za<\/div><\/div><\/div><div class=\"vcex-list_item vcex-module wpex-m-0 wpex-max-w-100 wpex-mb-5\"><a href=\"https:\/\/wa.me\/27824529342\" class=\"vcex-list-item-link wpex-no-underline\"><div class=\"vcex-list-item-inner wpex-inline-flex wpex-flex-no-wrap\"><div class=\"vcex-list-item-icon wpex-mr-10\"><div class=\"vcex-list-item-icon-inner vcex-icon-wrap wpex-inline-flex wpex-justify-center wpex-items-center wpex-leading-none wpex-child-inherit-color\"><span class=\"wpex-icon--w wpex-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H384c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zm90.7 96.7c9.7-2.6 19.9 2.3 23.7 11.6l20 48c3.4 8.2 1 17.6-5.8 23.2L168 231.7c16.6 35.2 45.1 63.7 80.3 80.3l20.2-24.7c5.6-6.8 15-9.2 23.2-5.8l48 20c9.3 3.9 14.2 14 11.6 23.7l-12 44C336.9 378 329 384 320 384C196.3 384 96 283.7 96 160c0-9 6-16.9 14.7-19.3l44-12z\"\/><\/svg><\/span><\/div><\/div><div class=\"vcex-list-item-text vcex-content wpex-flex-grow\">Lizelle: 082 452 9342<\/div><\/div><\/a><\/div><div class=\"vcex-list_item vcex-module wpex-m-0 wpex-max-w-100 wpex-mb-5\"><a href=\"https:\/\/wa.me\/27796947200\" class=\"vcex-list-item-link wpex-no-underline\"><div class=\"vcex-list-item-inner wpex-inline-flex wpex-flex-no-wrap\"><div class=\"vcex-list-item-icon wpex-mr-10\"><div class=\"vcex-list-item-icon-inner vcex-icon-wrap wpex-inline-flex wpex-justify-center wpex-items-center wpex-leading-none wpex-child-inherit-color\"><span class=\"wpex-icon--w wpex-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H384c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zm90.7 96.7c9.7-2.6 19.9 2.3 23.7 11.6l20 48c3.4 8.2 1 17.6-5.8 23.2L168 231.7c16.6 35.2 45.1 63.7 80.3 80.3l20.2-24.7c5.6-6.8 15-9.2 23.2-5.8l48 20c9.3 3.9 14.2 14 11.6 23.7l-12 44C336.9 378 329 384 320 384C196.3 384 96 283.7 96 160c0-9 6-16.9 14.7-19.3l44-12z\"\/><\/svg><\/span><\/div><\/div><div class=\"vcex-list-item-text vcex-content wpex-flex-grow\">Minda: 079 694 7200<\/div><\/div><\/a><\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:15px;\"><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f24-o1\" lang=\"en-ZA\" dir=\"ltr\" data-wpcf7-id=\"24\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/new\/wp-json\/wp\/v2\/pages\/18#wpcf7-f24-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"24\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_ZA\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f24-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpex-row clr\">\n\t<div class=\"span_1_of_2 col col-1 clr\">\n\t\t<p><label>Name and surname*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label>Email address*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div><!-- .span_1_of_2 -->\n\t<div class=\"span_1_of_2 col clr\">\n\t\t<p><label>Contact Number*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-number\" \/><\/span> <\/label><br \/>\n<label>Subject<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div><!-- .span_1_of_2 -->\n<\/div><!-- .wpex-row -->\n<p><label>Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:15px;\"><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1775726148476{padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;] Contact Us [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry","entry","no-media"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":17,"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":2015,"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/pages\/18\/revisions\/2015"}],"wp:attachment":[{"href":"https:\/\/www.wowven.co.za\/new\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}